{"id":105,"date":"2018-08-20T17:06:02","date_gmt":"2018-08-20T17:06:02","guid":{"rendered":"http:\/\/themenectar.com\/demo\/salient-ecommerce-creative\/?page_id=105"},"modified":"2025-04-11T15:54:24","modified_gmt":"2025-04-11T15:54:24","slug":"ecommerce-creative-home-page","status":"publish","type":"page","link":"https:\/\/getprime.ae\/ar\/","title":{"rendered":"eCommerce Creative Home Page"},"content":{"rendered":"<div id=\"main-slider-wrapper\"  data-column-margin=\"default\" data-midnight=\"dark\"  class=\"wpb_row vc_row-fluid vc_row prime-container\"  style=\"padding-top: 0px; padding-bottom: 0px; \"><div class=\"row-bg-wrap\" data-bg-animation=\"none\" data-bg-animation-delay=\"\" data-bg-overlay=\"false\"><div class=\"inner-wrap row-bg-layer\" ><div class=\"row-bg viewport-desktop using-bg-color\"  style=\"background-color: #ffffff; \"><\/div><\/div><\/div><div class=\"row_col_wrap_12 col span_12 dark left\">\n\t<div  class=\"vc_col-sm-12 wpb_column column_container vc_column_container col no-extra-padding inherit_tablet inherit_phone\"  data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\" >\n\t\t<div class=\"vc_column-inner\" >\n\t\t\t<div class=\"wpb_wrapper\">\n\t\t\t\t<div  data-transition=\"slide\" data-overall_style=\"classic\" data-flexible-height=\"true\" data-animate-in-effect=\"none\" data-fullscreen=\"true\" data-button-sizing=\"regular\" data-button-styling=\"btn_with_count\" data-autorotate=\"5000\" data-parallax=\"false\" data-parallax-disable-mobile=\"\" data-caption-trans=\"fade_in_from_bottom\" data-parallax-style=\"bg_only\" data-bg-animation=\"none\" data-full-width=\"true\" class=\"nectar-slider-wrap\" id=\"nectar-slider-instance-1\"><div class=\"swiper-container\"  data-tho=\"auto\" data-tco=\"auto\" data-pho=\"auto\" data-pco=\"auto\" data-loop=\"true\" data-height=\"650\" data-min-height=\"\" data-arrows=\"true\" data-bullets=\"false\" data-bullet_style=\"see_through\" data-bullet_position=\"bottom\" data-desktop-swipe=\"false\" data-settings=\"\"> <div class=\"swiper-wrapper\"><div class=\"swiper-slide\" data-desktop-content-width=\"auto\" data-tablet-content-width=\"auto\" data-bg-alignment=\"center\" data-color-scheme=\"light\" data-x-pos=\"centered\" data-y-pos=\"middle\" ><div class=\"slide-bg-wrap\"><div class=\"image-bg\" style=\"background-image: url(https:\/\/getprime.ae\/wp-content\/uploads\/2024\/10\/fresh-coffee-steams-wooden-table-close-up-generative-ai-1-scaled.jpg);\"> &nbsp; <\/div><\/div><div class=\"container\">\n\t\t\t\t\t\t<div class=\"content\"><h2 class=\"ns-heading-el\">\u0627\u0643\u062a\u0634\u0641 \u0627\u0644\u0641\u0631\u0642 \u0627\u0644\u0623\u0633\u0627\u0633\u064a<\/h2><p  ><span>PRIME Official Distributer for PRIME , HiBREW &amp; STARSEEKER<\/span><\/p><div class=\"buttons\"><div class=\"button solid_color\">\n\t\t\t\t\t\t\t\t\t\t <a class=\"primary-color\" href=\"https:\/\/getprime.ae\/ar\/shop\/\">\u062a\u0633\u0648\u0642 \u0627\u0644\u0622\u0646<\/a>\n\t\t\t\t\t\t\t\t\t\t<\/div><\/div><\/div>\n\t\t\t\t\t\t\t\t<\/div><!--\/container--><div class=\"video-texture\"> <span class=\"ie-fix\"><\/span> <\/div><\/div> <!--\/swiper-slide--><\/div><div class=\"nectar-slider-loading\"> <span class=\"loading-icon none\">   <\/span> <\/div> <\/div> \n\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t<\/div> \n\t\t<\/div>\n\t<\/div> \n<\/div><\/div>\n\t\t<div id=\"fws_6a04ffa7811f8\"  data-column-margin=\"default\" data-midnight=\"dark\"  class=\"wpb_row vc_row-fluid vc_row  top_margin_20px\"  style=\"padding-top: 0px; padding-bottom: 0px; \"><div class=\"row-bg-wrap\" data-bg-animation=\"none\" data-bg-animation-delay=\"\" data-bg-overlay=\"false\"><div class=\"inner-wrap row-bg-layer\" ><div class=\"row-bg viewport-desktop using-bg-color\"  style=\"background-color: #f9f9f9; \"><\/div><\/div><\/div><div class=\"row_col_wrap_12 col span_12 dark center\">\n\t<div  class=\"vc_col-sm-12 wpb_column column_container vc_column_container col no-extra-padding max_width_desktop_500px inherit_tablet inherit_phone\"  data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\" >\n\t\t<div class=\"vc_column-inner\" >\n\t\t\t<div class=\"wpb_wrapper\">\n\t\t\t\t\n<div class=\"wpb_text_column wpb_content_element  wpb_animate_when_almost_visible wpb_fadeInUp fadeInUp vc_custom_1729356098853\" >\n\t<div class=\"wpb_wrapper\">\n\t\t<h3 style=\"text-align: center;\"><span style=\"color: #ff0000;\"><strong>\u0646\u0642\u062f\u0645<\/strong><\/span><\/h3>\n<h2 style=\"text-align: center;\"><strong>PRIME ULTIMO<\/strong><\/h2>\n\t<\/div>\n<\/div>\n\n\n\n<div  data-transition=\"slide\" data-overall_style=\"classic\" data-flexible-height=\"\" data-animate-in-effect=\"none\" data-fullscreen=\"false\" data-button-sizing=\"regular\" data-button-styling=\"btn_with_count\" data-autorotate=\"5000\" data-parallax=\"false\" data-parallax-disable-mobile=\"\" data-caption-trans=\"fade_in_from_bottom\" data-parallax-style=\"bg_only\" data-bg-animation=\"none\" data-full-width=\"false\" class=\"nectar-slider-wrap\" id=\"nectar-slider-instance-2\"><div class=\"swiper-container\"  data-tho=\"auto\" data-tco=\"auto\" data-pho=\"auto\" data-pco=\"auto\" data-loop=\"true\" data-height=\"500\" data-min-height=\"\" data-arrows=\"false\" data-bullets=\"true\" data-bullet_style=\"scale\" data-bullet_position=\"bottom\" data-desktop-swipe=\"true\" data-settings=\"\"> <div class=\"swiper-wrapper\"><div class=\"swiper-slide\" data-desktop-content-width=\"auto\" data-tablet-content-width=\"auto\" data-bg-alignment=\"center\" data-color-scheme=\"light\" data-x-pos=\"left\" data-y-pos=\"middle\" ><div class=\"slide-bg-wrap\"><div class=\"image-bg\" style=\"background-image: url(https:\/\/getprime.ae\/wp-content\/uploads\/2024\/10\/P_1.png);\"> &nbsp; <\/div><\/div><div class=\"video-texture\"> <span class=\"ie-fix\"><\/span> <\/div><a href=\"https:\/\/getprime.ae\/ar\/product\/prime-ultimo\/\" class=\"entire-slide-link\"> <span class=\"ie-fix\"><\/span> <\/a><\/div> <!--\/swiper-slide--><div class=\"swiper-slide\" data-desktop-content-width=\"auto\" data-tablet-content-width=\"auto\" data-bg-alignment=\"center\" data-color-scheme=\"light\" data-x-pos=\"left\" data-y-pos=\"middle\" ><div class=\"slide-bg-wrap\"><div class=\"image-bg\" style=\"background-image: url(https:\/\/getprime.ae\/wp-content\/uploads\/2024\/10\/P_3.png);\"> &nbsp; <\/div><\/div><div class=\"video-texture\"> <span class=\"ie-fix\"><\/span> <\/div><a href=\"https:\/\/getprime.ae\/ar\/product\/prime-ultimo\/\" class=\"entire-slide-link\"> <span class=\"ie-fix\"><\/span> <\/a><\/div> <!--\/swiper-slide--><div class=\"swiper-slide\" data-desktop-content-width=\"auto\" data-tablet-content-width=\"auto\" data-bg-alignment=\"center\" data-color-scheme=\"light\" data-x-pos=\"left\" data-y-pos=\"middle\" ><div class=\"slide-bg-wrap\"><div class=\"image-bg\" style=\"background-image: url(https:\/\/getprime.ae\/wp-content\/uploads\/2024\/10\/P_2.png);\"> &nbsp; <\/div><\/div><div class=\"video-texture\"> <span class=\"ie-fix\"><\/span> <\/div><a href=\"https:\/\/getprime.ae\/ar\/product\/prime-ultimo\/\" class=\"entire-slide-link\"> <span class=\"ie-fix\"><\/span> <\/a><\/div> <!--\/swiper-slide--><div class=\"swiper-slide\" data-desktop-content-width=\"auto\" data-tablet-content-width=\"auto\" data-bg-alignment=\"center\" data-color-scheme=\"light\" data-x-pos=\"left\" data-y-pos=\"middle\" ><div class=\"slide-bg-wrap\"><div class=\"image-bg\" style=\"background-image: url(https:\/\/getprime.ae\/wp-content\/uploads\/2024\/10\/P_4.png);\"> &nbsp; <\/div><\/div><div class=\"video-texture\"> <span class=\"ie-fix\"><\/span> <\/div><a href=\"https:\/\/getprime.ae\/ar\/product\/prime-ultimo\/\" class=\"entire-slide-link\"> <span class=\"ie-fix\"><\/span> <\/a><\/div> <!--\/swiper-slide--><\/div><div class=\"container normal-container slider-pagination-wrap\"><div class=\"slider-pagination\"><\/div><\/div><div class=\"nectar-slider-loading\"> <span class=\"loading-icon none\">   <\/span> <\/div> <\/div> \n\t\t\t\t\t\n\t\t\t\t\t<\/div><div  data-transition=\"slide\" data-overall_style=\"classic\" data-flexible-height=\"\" data-animate-in-effect=\"none\" data-fullscreen=\"false\" data-button-sizing=\"regular\" data-button-styling=\"btn_with_count\" data-autorotate=\"5000\" data-parallax=\"false\" data-parallax-disable-mobile=\"\" data-caption-trans=\"fade_in_from_bottom\" data-parallax-style=\"bg_only\" data-bg-animation=\"none\" data-full-width=\"false\" class=\"nectar-slider-wrap\" id=\"nectar-slider-instance-3\"><div class=\"swiper-container\"  data-tho=\"auto\" data-tco=\"auto\" data-pho=\"auto\" data-pco=\"auto\" data-loop=\"true\" data-height=\"1080\" data-min-height=\"\" data-arrows=\"false\" data-bullets=\"true\" data-bullet_style=\"scale\" data-bullet_position=\"bottom\" data-desktop-swipe=\"true\" data-settings=\"\"> <div class=\"swiper-wrapper\"><div class=\"swiper-slide\" data-desktop-content-width=\"auto\" data-tablet-content-width=\"auto\" data-bg-alignment=\"center\" data-color-scheme=\"light\" data-x-pos=\"left\" data-y-pos=\"middle\" ><div class=\"slide-bg-wrap\"><div class=\"image-bg\" style=\"background-image: url(https:\/\/getprime.ae\/wp-content\/uploads\/2024\/10\/P_1.png);\"> &nbsp; <\/div><\/div><div class=\"video-texture\"> <span class=\"ie-fix\"><\/span> <\/div><a href=\"https:\/\/getprime.ae\/ar\/product\/prime-ultimo\/\" class=\"entire-slide-link\"> <span class=\"ie-fix\"><\/span> <\/a><\/div> <!--\/swiper-slide--><div class=\"swiper-slide\" data-desktop-content-width=\"auto\" data-tablet-content-width=\"auto\" data-bg-alignment=\"center\" data-color-scheme=\"light\" data-x-pos=\"left\" data-y-pos=\"middle\" ><div class=\"slide-bg-wrap\"><div class=\"image-bg\" style=\"background-image: url(https:\/\/getprime.ae\/wp-content\/uploads\/2024\/10\/P_2.png);\"> &nbsp; <\/div><\/div><div class=\"video-texture\"> <span class=\"ie-fix\"><\/span> <\/div><a href=\"https:\/\/getprime.ae\/ar\/product\/prime-ultimo\/\" class=\"entire-slide-link\"> <span class=\"ie-fix\"><\/span> <\/a><\/div> <!--\/swiper-slide--><div class=\"swiper-slide\" data-desktop-content-width=\"auto\" data-tablet-content-width=\"auto\" data-bg-alignment=\"center\" data-color-scheme=\"light\" data-x-pos=\"left\" data-y-pos=\"middle\" ><div class=\"slide-bg-wrap\"><div class=\"image-bg\" style=\"background-image: url(https:\/\/getprime.ae\/wp-content\/uploads\/2024\/10\/P_3.png);\"> &nbsp; <\/div><\/div><div class=\"video-texture\"> <span class=\"ie-fix\"><\/span> <\/div><a href=\"https:\/\/getprime.ae\/ar\/product\/prime-ultimo\/\" class=\"entire-slide-link\"> <span class=\"ie-fix\"><\/span> <\/a><\/div> <!--\/swiper-slide--><div class=\"swiper-slide\" data-desktop-content-width=\"auto\" data-tablet-content-width=\"auto\" data-bg-alignment=\"center\" data-color-scheme=\"light\" data-x-pos=\"left\" data-y-pos=\"middle\" ><div class=\"slide-bg-wrap\"><div class=\"image-bg\" style=\"background-image: url(https:\/\/getprime.ae\/wp-content\/uploads\/2024\/10\/P_4.png);\"> &nbsp; <\/div><\/div><div class=\"video-texture\"> <span class=\"ie-fix\"><\/span> <\/div><a href=\"https:\/\/getprime.ae\/ar\/product\/prime-ultimo\/\" class=\"entire-slide-link\"> <span class=\"ie-fix\"><\/span> <\/a><\/div> <!--\/swiper-slide--><\/div><div class=\"container normal-container slider-pagination-wrap\"><div class=\"slider-pagination\"><\/div><\/div><div class=\"nectar-slider-loading\"> <span class=\"loading-icon none\">   <\/span> <\/div> <\/div> \n\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t<\/div> \n\t\t<\/div>\n\t<\/div> \n<\/div><\/div>\n\t\t<div id=\"fws_6a04ffa787150\"  data-column-margin=\"default\" data-midnight=\"dark\"  class=\"wpb_row vc_row-fluid vc_row\"  style=\"padding-top: 0px; padding-bottom: 0px; \"><div class=\"row-bg-wrap\" data-bg-animation=\"none\" data-bg-animation-delay=\"\" data-bg-overlay=\"false\"><div class=\"inner-wrap row-bg-layer\" ><div class=\"row-bg viewport-desktop using-bg-color\"  style=\"background-color: #F9F9F9; \"><\/div><\/div><\/div><div class=\"row_col_wrap_12 col span_12 dark left\">\n\t<div  class=\"vc_col-sm-12 wpb_column column_container vc_column_container col no-extra-padding inherit_tablet inherit_phone\"  data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\" >\n\t\t<div class=\"vc_column-inner\" >\n\t\t\t<div class=\"wpb_wrapper\">\n\t\t\t\t<div class=\"nectar-category-grid\" data-style=\"content_overlaid\" data-columns=\"4\" data-h-tag=\"default\" data-text-style=\"\" data-grid-spacing=\"10px\" data-alignment=\"bottom_left\" data-text-color=\"dark\" data-text-hover-color=\"light\" data-shadow-hover=\"\" data-masonry=\"\"><div class=\"nectar-category-grid-item\"> <div class=\"inner\"> <a class=\"nectar-category-grid-link\" href=\"https:\/\/getprime.ae\/ar\/product-category\/starseeker\/\" aria-label=\"STARSEEKER\"><\/a><div class=\"nectar-category-grid-item-bg\" style=\"background-image:url(https:\/\/getprime.ae\/wp-content\/uploads\/2025\/04\/images-3.png);\"><\/div><div class=\"bg-overlay\" style=\" background-color: #000000;\" data-opacity=\"0\" data-hover-opacity=\"0.3\"><\/div><div class=\"content\" data-subtext-vis=\"on_hover\" data-subtext=\"cat_item_count\" ><h3 class=\"cat-heading\">STARSEEKER<\/h3><span class=\"subtext\">0 products<\/span><\/div><\/div><\/div><div class=\"nectar-category-grid-item\"> <div class=\"inner\"> <a class=\"nectar-category-grid-link\" href=\"https:\/\/getprime.ae\/ar\/product-category\/prime\/\" aria-label=\"Ultimate 7 in 1\"><\/a><div class=\"nectar-category-grid-item-bg\" style=\"background-image:url(https:\/\/getprime.ae\/wp-content\/uploads\/2024\/10\/prime-1024x944.png);\"><\/div><div class=\"bg-overlay\" style=\" background-color: #000000;\" data-opacity=\"0\" data-hover-opacity=\"0.3\"><\/div><div class=\"content\" data-subtext-vis=\"on_hover\" data-subtext=\"cat_item_count\" ><h3 class=\"cat-heading\">Ultimate 7 in 1<\/h3><span class=\"subtext\">2 products<\/span><\/div><\/div><\/div><div class=\"nectar-category-grid-item\"> <div class=\"inner\"> <a class=\"nectar-category-grid-link\" href=\"https:\/\/getprime.ae\/ar\/product-category\/mugs-cups\/\" aria-label=\"\u0623\u0643\u0648\u0627\u0628 \u0648\u0623\u0643\u0648\u0627\u0628\"><\/a><div class=\"nectar-category-grid-item-bg\" ><\/div><div class=\"bg-overlay\" style=\" background-color: #000000;\" data-opacity=\"0\" data-hover-opacity=\"0.3\"><\/div><div class=\"content\" data-subtext-vis=\"on_hover\" data-subtext=\"cat_item_count\" ><h3 class=\"cat-heading\">\u0623\u0643\u0648\u0627\u0628 \u0648\u0623\u0643\u0648\u0627\u0628<\/h3><span class=\"subtext\">5 products<\/span><\/div><\/div><\/div><div class=\"nectar-category-grid-item\"> <div class=\"inner\"> <a class=\"nectar-category-grid-link\" href=\"https:\/\/getprime.ae\/ar\/product-category\/hibrew\/\" aria-label=\"HiBREW Official distributer\"><\/a><div class=\"nectar-category-grid-item-bg\" style=\"background-image:url(https:\/\/getprime.ae\/wp-content\/uploads\/2024\/10\/Hibrew-1024x921.png);\"><\/div><div class=\"bg-overlay\" style=\" background-color: #000000;\" data-opacity=\"0\" data-hover-opacity=\"0.3\"><\/div><div class=\"content\" data-subtext-vis=\"on_hover\" data-subtext=\"cat_item_count\" ><h3 class=\"cat-heading\">HiBREW Official distributer<\/h3><span class=\"subtext\">19 products<\/span><\/div><\/div><\/div><\/div>\n\t\t\t<\/div> \n\t\t<\/div>\n\t<\/div> \n<\/div><\/div>\n\t\t<div id=\"fws_6a04ffa789feb\"  data-column-margin=\"default\" data-midnight=\"light\" data-top-percent=\"8%\" data-bottom-percent=\"8%\"  class=\"wpb_row vc_row-fluid vc_row full-width-content vc_row-o-equal-height vc_row-flex vc_row-o-content-top parallax_section hide\"  style=\"padding-top: calc(100vw * 0.08); padding-bottom: calc(100vw * 0.08); \"><div class=\"row-bg-wrap\" data-bg-animation=\"none\" data-bg-animation-delay=\"\" data-bg-overlay=\"true\"><div class=\"inner-wrap row-bg-layer using-image\" ><div class=\"row-bg viewport-desktop using-image using-bg-color\" data-parallax-speed=\"fast\" style=\"background-image: url(https:\/\/getprime.ae\/wp-content\/uploads\/2024\/10\/PC2160x1080-4_dbf67e43-c910-42d8-a15f-c02ac27d0966.webp); background-position: center center; background-repeat: no-repeat; background-color: #333333; \"><\/div><\/div><div class=\"row-bg-overlay row-bg-layer\" style=\"background-color:rgba(10,10,10,0.45);  opacity: 0.3; \"><\/div><\/div><div class=\"row_col_wrap_12 col span_12 light left\">\n\t<div  class=\"vc_col-sm-12 wpb_column column_container vc_column_container col no-extra-padding inherit_tablet inherit_phone\"  data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\" >\n\t\t<div class=\"vc_column-inner\" >\n\t\t\t<div class=\"wpb_wrapper\">\n\t\t\t\t<div id=\"fws_6a04ffa78a2b7\" data-midnight=\"\" data-column-margin=\"default\" class=\"wpb_row vc_row-fluid vc_row inner_row vc_row-o-equal-height vc_row-flex vc_row-o-content-middle\"  style=\"\"><div class=\"row-bg-wrap\"> <div class=\"row-bg\" ><\/div> <\/div><div class=\"row_col_wrap_12_inner col span_12  left\">\n\t<div  class=\"vc_col-sm-12 wpb_column column_container vc_column_container col child_column has-animation padding-5-percent inherit_tablet inherit_phone\"   data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-animation=\"fade-in-from-bottom\" data-delay=\"0\" >\n\t\t<div class=\"vc_column-inner\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t\n<div class=\"wpb_text_column wpb_content_element  vc_custom_1728148750542\" >\n\t<div class=\"wpb_wrapper\">\n\t\t<h4 style=\"text-align: left;\">Light &amp; Free Collection<\/h4>\n\t<\/div>\n<\/div>\n\n\n\n\n<div class=\"wpb_text_column wpb_content_element  vc_custom_1728148754890\" >\n\t<div class=\"wpb_wrapper\">\n\t\t<h2 style=\"text-align: left;\">Adventure Clothes<\/h2>\n\t<\/div>\n<\/div>\n\n\n\n\n<div class=\"wpb_text_column wpb_content_element  vc_custom_1728148791089\" style=\" max-width: 500px; display: inline-block;\">\n\t<div class=\"wpb_wrapper\">\n\t\t<p style=\"text-align: left;\">Far far away, behind the word mountains, far from the countries Vokalia and Consonantia, there live the blind texts. Separated they live.<\/p>\n\t<\/div>\n<\/div>\n\n\n\n<div class=\"nectar-cta  alignment_tablet_default alignment_phone_default display_tablet_inherit display_phone_inherit\" data-color=\"default\" data-using-bg=\"false\" data-display=\"block\" data-style=\"underline\" data-alignment=\"left\" data-text-color=\"custom\" ><h5 style=\"color: #ffffff;\"> <span class=\"link_wrap\" ><a  class=\"link_text\" style=\"border-color: #ffffff;\" role=\"button\" href=\"https:\/\/www.hibrew.ae\">HIBREW \u0642\u0645 \u0628\u0632\u064a\u0627\u0631\u0629<\/a><\/span><\/h5><\/div>\n\t\t<\/div> \n\t<\/div>\n\t<\/div> \n<\/div><\/div>\n\t\t\t<\/div> \n\t\t<\/div>\n\t<\/div> \n<\/div><\/div>\n\t\t<div id=\"fws_6a04ffa78b5c7\"  data-column-margin=\"default\" data-midnight=\"dark\"  class=\"wpb_row vc_row-fluid vc_row full-width-content vc_row-o-equal-height vc_row-flex vc_row-o-content-top hide\"  style=\"padding-top: 0px; padding-bottom: 0px; \"><div class=\"row-bg-wrap\" data-bg-animation=\"none\" data-bg-animation-delay=\"\" data-bg-overlay=\"false\"><div class=\"inner-wrap row-bg-layer\" ><div class=\"row-bg viewport-desktop using-bg-color\"  style=\"background-color: #ffffff; \"><\/div><\/div><\/div><div class=\"row_col_wrap_12 col span_12 dark left\">\n\t<div  class=\"vc_col-sm-12 wpb_column column_container vc_column_container col no-extra-padding inherit_tablet inherit_phone\"  data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\" >\n\t\t<div class=\"vc_column-inner\" >\n\t\t\t<div class=\"wpb_wrapper\">\n\t\t\t\t<div class=\"nectar-category-grid\" data-style=\"content_overlaid\" data-columns=\"3\" data-h-tag=\"default\" data-text-style=\"\" data-grid-spacing=\"10px\" data-alignment=\"bottom_left\" data-text-color=\"light\" data-text-hover-color=\"light\" data-shadow-hover=\"\" data-masonry=\"yes\"><div class=\"nectar-category-grid-item\"> <div class=\"inner\"> <a class=\"nectar-category-grid-link\" href=\"https:\/\/getprime.ae\/ar\/product-category\/starseeker\/\" aria-label=\"STARSEEKER\"><\/a><div class=\"nectar-category-grid-item-bg\" style=\"background-image:url(https:\/\/getprime.ae\/wp-content\/uploads\/2025\/04\/images-3.png);\"><\/div><div class=\"bg-overlay\" style=\" background-color: #000000;\" data-opacity=\"0.3\" data-hover-opacity=\"0.5\"><\/div><div class=\"content\" data-subtext-vis=\"on_hover\" data-subtext=\"cat_item_count\" ><h3 class=\"cat-heading\">STARSEEKER<\/h3><span class=\"subtext\">0 products<\/span><\/div><\/div><\/div><div class=\"nectar-category-grid-item\"> <div class=\"inner\"> <a class=\"nectar-category-grid-link\" href=\"https:\/\/getprime.ae\/ar\/product-category\/prime\/\" aria-label=\"Ultimate 7 in 1\"><\/a><div class=\"nectar-category-grid-item-bg\" style=\"background-image:url(https:\/\/getprime.ae\/wp-content\/uploads\/2024\/10\/prime-1024x944.png);\"><\/div><div class=\"bg-overlay\" style=\" background-color: #000000;\" data-opacity=\"0.3\" data-hover-opacity=\"0.5\"><\/div><div class=\"content\" data-subtext-vis=\"on_hover\" data-subtext=\"cat_item_count\" ><h3 class=\"cat-heading\">Ultimate 7 in 1<\/h3><span class=\"subtext\">2 products<\/span><\/div><\/div><\/div><div class=\"nectar-category-grid-item\"> <div class=\"inner\"> <a class=\"nectar-category-grid-link\" href=\"https:\/\/getprime.ae\/ar\/product-category\/mugs-cups\/\" aria-label=\"\u0623\u0643\u0648\u0627\u0628 \u0648\u0623\u0643\u0648\u0627\u0628\"><\/a><div class=\"nectar-category-grid-item-bg\" ><\/div><div class=\"bg-overlay\" style=\" background-color: #000000;\" data-opacity=\"0.3\" data-hover-opacity=\"0.5\"><\/div><div class=\"content\" data-subtext-vis=\"on_hover\" data-subtext=\"cat_item_count\" ><h3 class=\"cat-heading\">\u0623\u0643\u0648\u0627\u0628 \u0648\u0623\u0643\u0648\u0627\u0628<\/h3><span class=\"subtext\">5 products<\/span><\/div><\/div><\/div><div class=\"nectar-category-grid-item\"> <div class=\"inner\"> <a class=\"nectar-category-grid-link\" href=\"https:\/\/getprime.ae\/ar\/product-category\/hibrew\/\" aria-label=\"HiBREW Official distributer\"><\/a><div class=\"nectar-category-grid-item-bg\" style=\"background-image:url(https:\/\/getprime.ae\/wp-content\/uploads\/2024\/10\/Hibrew-1024x921.png);\"><\/div><div class=\"bg-overlay\" style=\" background-color: #000000;\" data-opacity=\"0.3\" data-hover-opacity=\"0.5\"><\/div><div class=\"content\" data-subtext-vis=\"on_hover\" data-subtext=\"cat_item_count\" ><h3 class=\"cat-heading\">HiBREW Official distributer<\/h3><span class=\"subtext\">19 products<\/span><\/div><\/div><\/div><\/div>\n\t\t\t<\/div> \n\t\t<\/div>\n\t<\/div> \n<\/div><\/div>\n\t\t<div id=\"fws_6a04ffa78c289\"  data-column-margin=\"default\" data-midnight=\"dark\"  class=\"wpb_row vc_row-fluid vc_row full-width-content vc_row-o-equal-height vc_row-flex vc_row-o-content-top\"  style=\"padding-top: 50px; padding-bottom: 40px; \"><div class=\"row-bg-wrap\" data-bg-animation=\"none\" data-bg-animation-delay=\"\" data-bg-overlay=\"false\"><div class=\"inner-wrap row-bg-layer\" ><div class=\"row-bg viewport-desktop using-bg-color\"  style=\"background-color: #ffffff; \"><\/div><\/div><\/div><div class=\"row_col_wrap_12 col span_12 dark left\">\n\t<div  class=\"vc_col-sm-12 wpb_column column_container vc_column_container col has-animation no-extra-padding inherit_tablet inherit_phone\"  data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-animation=\"fade-in\" data-delay=\"0\" >\n\t\t<div class=\"vc_column-inner\" >\n\t\t\t<div class=\"wpb_wrapper\">\n\t\t\t\t<div class=\"woocommerce columns-dynamic\"><\/div>\n\t\t\t<\/div> \n\t\t<\/div>\n\t<\/div> \n<\/div><\/div>\n\t\t<div id=\"fws_6a04ffa78d2e0\"  data-column-margin=\"default\" data-midnight=\"dark\" data-top-percent=\"3%\" data-bottom-percent=\"3%\"  class=\"wpb_row vc_row-fluid vc_row full-width-section\"  style=\"padding-top: calc(100vw * 0.03); padding-bottom: calc(100vw * 0.03); \"><div class=\"row-bg-wrap\" data-bg-animation=\"none\" data-bg-animation-delay=\"\" data-bg-overlay=\"false\"><div class=\"inner-wrap row-bg-layer\" ><div class=\"row-bg viewport-desktop using-bg-color\"  style=\"background-color: #ffffff; \"><\/div><\/div><\/div><div class=\"row_col_wrap_12 col span_12 dark left\">\n\t<div  class=\"vc_col-sm-12 wpb_column column_container vc_column_container col no-extra-padding inherit_tablet inherit_phone\"  data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\" >\n\t\t<div class=\"vc_column-inner\" >\n\t\t\t<div class=\"wpb_wrapper\">\n\t\t\t\t<div class=\"divider-wrap\" data-alignment=\"default\"><div style=\"height: 40px;\" class=\"divider\"><\/div><\/div>\n<div class=\"wpb_text_column wpb_content_element  wpb_animate_when_almost_visible wpb_fadeInUp fadeInUp vc_custom_1728600325187\" >\n\t<div class=\"wpb_wrapper\">\n\t\t<h3 style=\"text-align: center;\">\u0622\u0644\u0627\u062a \u0627\u0644\u0642\u0647\u0648\u0629 \u0627\u0644\u0645\u062a\u0645\u064a\u0632\u0629<\/h3>\n\t<\/div>\n<\/div>\n\n\n\n<div id=\"fws_6a04ffa78da22\" data-midnight=\"\" data-column-margin=\"default\" class=\"wpb_row vc_row-fluid vc_row inner_row  vc_custom_1504187365562\"  style=\"\"><div class=\"row-bg-wrap\"> <div class=\"row-bg\" ><\/div> <\/div><div class=\"row_col_wrap_12_inner col span_12  left\">\n\t<div  class=\"vc_col-sm-4 wpb_column column_container vc_column_container col child_column no-extra-padding inherit_tablet inherit_phone\"   data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\" >\n\t\t<div class=\"vc_column-inner\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<div class=\"nectar-fancy-box   has-animation\" data-style=\"color_box_hover\" data-animation=\"grow-in\" data-hover-o=\"default\" data-border-radius=\"default\" data-border=\"true\" data-box-color-opacity=\"1\" data-delay=\"0\" data-alignment=\"center\" data-color=\"accent-color\" ><div class=\"box-inner-wrap\"><div class=\"box-bg\" ><\/div> <div class=\"inner\" style=\"min-height: 100px\"><div class=\"inner-wrap\"><i class=\"icon-default-style steadysets-icon-align-center\" data-color=\"accent-color\" style=\"font-size: 20px!important; line-height: 20px!important;\"><\/i>\n<h4>\u0636\u0645\u0627\u0646<\/h4>\n<p>\u0644\u0645\u062f\u0629 \u0633\u0646\u0629<br \/>\n\u00ad<\/div><\/div>  <\/div> <\/div>\n\t\t<\/div> \n\t<\/div>\n\t<\/div> \n\n\t<div  class=\"vc_col-sm-4 wpb_column column_container vc_column_container col child_column no-extra-padding inherit_tablet inherit_phone\"   data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\" >\n\t\t<div class=\"vc_column-inner\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<div class=\"nectar-fancy-box   has-animation\" data-style=\"color_box_hover\" data-animation=\"grow-in\" data-hover-o=\"default\" data-border-radius=\"default\" data-border=\"true\" data-box-color-opacity=\"1\" data-delay=\"100\" data-alignment=\"center\" data-color=\"accent-color\" ><div class=\"box-inner-wrap\"><div class=\"box-bg\" ><\/div> <div class=\"inner\" style=\"min-height: 100px\"><div class=\"inner-wrap\"><i class=\"icon-default-style fa fa-star-o\" data-color=\"accent-color\" style=\"font-size: 20px!important; line-height: 20px!important;\"><\/i>\n<h4>\u0623\u0641\u0636\u0644 \u062c\u0648\u062f\u0629<\/h4>\n<p>\u0646\u062d\u0646 \u0646\u0635\u0646\u0639 \u0627\u0644\u0623\u0641\u0636\u0644<br \/>\n\u062c\u0648\u062f\u0629 \u0622\u0644\u0627\u062a \u0627\u0644\u0642\u0647\u0648\u0629.<\/div><\/div>  <\/div> <\/div>\n\t\t<\/div> \n\t<\/div>\n\t<\/div> \n\n\t<div  class=\"vc_col-sm-4 wpb_column column_container vc_column_container col child_column no-extra-padding inherit_tablet inherit_phone\"   data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\" >\n\t\t<div class=\"vc_column-inner\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<div class=\"nectar-fancy-box   has-animation\" data-style=\"color_box_hover\" data-animation=\"grow-in\" data-hover-o=\"default\" data-border-radius=\"default\" data-border=\"true\" data-box-color-opacity=\"1\" data-delay=\"200\" data-alignment=\"center\" data-color=\"accent-color\" ><div class=\"box-inner-wrap\"><div class=\"box-bg\" ><\/div> <div class=\"inner\" style=\"min-height: 100px\"><div class=\"inner-wrap\"><i class=\"icon-default-style fa fa-lock\" data-color=\"accent-color\" style=\"font-size: 20px!important; line-height: 20px!important;\"><\/i>\n<h4>\u0627\u0644\u0645\u062f\u0641\u0648\u0639\u0627\u062a \u0627\u0644\u0622\u0645\u0646\u0629<\/h4>\n<p>\u0646\u062d\u0646 \u0646\u062a\u0623\u0643\u062f \u0645\u0646 \u0630\u0644\u0643<br \/>\n\u064a\u062a\u0645 \u062a\u0623\u0645\u064a\u0646 \u0627\u0644\u062f\u0641\u0639 \u0627\u0644\u062e\u0627\u0635 \u0628\u0643.<\/div><\/div>  <\/div> <\/div>\n\t\t<\/div> \n\t<\/div>\n\t<\/div> \n<\/div><\/div><div class=\"divider-wrap\" data-alignment=\"default\"><div style=\"height: 40px;\" class=\"divider\"><\/div><\/div>\n\t\t\t<\/div> \n\t\t<\/div>\n\t<\/div> \n<\/div><\/div>\n\t\t<div id=\"fws_6a04ffa78eaac\"  data-column-margin=\"default\" data-midnight=\"light\" data-top-percent=\"8%\" data-bottom-percent=\"8%\"  class=\"wpb_row vc_row-fluid vc_row full-width-content vc_row-o-equal-height vc_row-flex vc_row-o-content-top\"  style=\"padding-top: calc(100vw * 0.08); padding-bottom: calc(100vw * 0.08); \"><div class=\"row-bg-wrap\" data-bg-animation=\"none\" data-bg-animation-delay=\"\" data-bg-overlay=\"true\"><div class=\"inner-wrap row-bg-layer using-image\" ><div class=\"row-bg viewport-desktop using-image\"  style=\"background-image: url(https:\/\/getprime.ae\/wp-content\/uploads\/2024\/10\/pexels-chevanon-302899-scaled.jpg); background-position: center center; background-repeat: no-repeat; \"><\/div><\/div><div class=\"row-bg-overlay row-bg-layer\" style=\"background-color:#0c0c0c;  opacity: 0.5; \"><\/div><\/div><div class=\"row_col_wrap_12 col span_12 light left\">\n\t<div  class=\"vc_col-sm-3 wpb_column column_container vc_column_container col no-extra-padding inherit_tablet inherit_phone\"  data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\" >\n\t\t<div class=\"vc_column-inner\" >\n\t\t\t<div class=\"wpb_wrapper\">\n\t\t\t\t\n\t\t\t<\/div> \n\t\t<\/div>\n\t<\/div> \n\n\t<div  class=\"vc_col-sm-6 wpb_column column_container vc_column_container col has-animation padding-5-percent inherit_tablet inherit_phone\"  data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-animation=\"fade-in-from-bottom\" data-delay=\"0\" >\n\t\t<div class=\"vc_column-inner\" >\n\t\t\t<div class=\"wpb_wrapper\">\n\t\t\t\t<div class=\"nectar-highlighted-text\" data-style=\"half_text\" data-exp=\"default\" data-using-custom-color=\"true\" data-animation-delay=\"false\" data-color=\"#ff0000\" data-color-gradient=\"\" style=\"\"><h2 style=\"text-align: center\">\u0643\u0644\u00a0 <a href=\"https:\/\/getprime.ae\/ar\/product-category\/prime\/\" target=\"_blank\" rel=\"noopener\"><em>PRIME<\/em><\/a> \u0622\u0644\u0629 \u0627\u0644\u0625\u0633\u0628\u0631\u064a\u0633\u0648 \u062a\u0634\u0628\u0647 \u0627\u0644\u062a\u062d\u0641\u0629 \u0627\u0644\u0641\u0646\u064a\u0629 \u0627\u0644\u0645\u0635\u0645\u0645\u0629 \u062e\u0635\u064a\u0635\u064b\u0627<\/h2>\n<\/div>\n\t\t\t<\/div> \n\t\t<\/div>\n\t<\/div> \n\n\t<div  class=\"vc_col-sm-3 wpb_column column_container vc_column_container col no-extra-padding inherit_tablet inherit_phone\"  data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\" >\n\t\t<div class=\"vc_column-inner\" >\n\t\t\t<div class=\"wpb_wrapper\">\n\t\t\t\t\n\t\t\t<\/div> \n\t\t<\/div>\n\t<\/div> \n<\/div><\/div>","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-105","page","type-page","status-publish"],"_links":{"self":[{"href":"https:\/\/getprime.ae\/ar\/wp-json\/wp\/v2\/pages\/105","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/getprime.ae\/ar\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/getprime.ae\/ar\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/getprime.ae\/ar\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/getprime.ae\/ar\/wp-json\/wp\/v2\/comments?post=105"}],"version-history":[{"count":57,"href":"https:\/\/getprime.ae\/ar\/wp-json\/wp\/v2\/pages\/105\/revisions"}],"predecessor-version":[{"id":3934,"href":"https:\/\/getprime.ae\/ar\/wp-json\/wp\/v2\/pages\/105\/revisions\/3934"}],"wp:attachment":[{"href":"https:\/\/getprime.ae\/ar\/wp-json\/wp\/v2\/media?parent=105"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}